{"id":202559,"date":"2017-09-13T00:10:08","date_gmt":"2017-09-13T00:10:08","guid":{"rendered":"http:\/\/www.vibia.com\/fr\/?p=202559"},"modified":"2017-10-26T12:35:57","modified_gmt":"2017-10-26T12:35:57","slug":"petites-astuces-pour-surmonter-le-blues-de-la-reprise","status":"publish","type":"post","link":"https:\/\/vibia.dev\/fr\/petites-astuces-pour-surmonter-le-blues-de-la-reprise\/","title":{"rendered":"Petites astuces pour surmonter le blues de la reprise"},"content":{"rendered":"<p>L\u2019\u00e9t\u00e9 est le moment o\u00f9 l\u2019on s\u2019\u00e9vade\u00a0: on fait un break pour \u00e9chapper \u00e0 la routine, on se d\u00e9tend, on se ressource. Mais quand les vacances se terminent, il est parfois difficile de retrouver la r\u00e9alit\u00e9 quotidienne. Nous avons demand\u00e9 \u00e0 certains de nos designers, architectes et cr\u00e9atifs pr\u00e9f\u00e9r\u00e9s de nous faire partager les astuces qui sont les leurs pour prolonger l\u2019effet vacances, afin de vous aider \u00e0 surmonter le blues de la reprise.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img class=\"lazyload wp-image-202872 aligncenter\" src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/isabelle-blase.jpg\" data-orig-src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/isabelle-blase.jpg\" alt=\"isabelle-blase\" width=\"360\" height=\"458\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27360%27%20height%3D%27458%27%20viewBox%3D%270%200%20360%20458%27%3E%3Crect%20width%3D%27360%27%20height%3D%27458%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/isabelle-blase-295x375.jpg 295w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/isabelle-blase-306x390.jpg 306w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/isabelle-blase-400x509.jpg 400w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/isabelle-blase-600x763.jpg 600w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/isabelle-blase.jpg 734w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/strong><\/p>\n<p><strong>Isabelle Blase,<\/strong> \u00e9tablie \u00e0 Frankfurt\/Main, Dipl\u00f4m\u00e9e en Architecture, Agent commerciale, architecte d\u2019\u00e9clairage, recommande de faire de courtes pauses au fil de la journ\u00e9e afin de tenir le cap. \u201cQuelques minutes de calme et de respiration apr\u00e8s une avalanche de mails et de conversations t\u00e9l\u00e9phoniques permettent de structurer la journ\u00e9e et le travail \u00e0 faire,\u201d dit-elle, \u201cet tout le monde a \u00e9videmment besoin d\u2019un bon caf\u00e9\u00a0!\u201d<\/p>\n<p><img class=\"lazyload alignnone wp-image-202890 size-full\" src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/susanna_cots.jpg\" data-orig-src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/susanna_cots.jpg\" width=\"734\" height=\"931\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27734%27%20height%3D%27931%27%20viewBox%3D%270%200%20734%20931%27%3E%3Crect%20width%3D%27734%27%20height%3D%27931%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/susanna_cots-296x375.jpg 296w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/susanna_cots-307x390.jpg 307w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/susanna_cots-400x507.jpg 400w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/susanna_cots-600x761.jpg 600w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/susanna_cots.jpg 734w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/p>\n<p><a href=\"http:\/\/www.susannacots.com\/\"><strong>Susana Cots<\/strong><\/a>, d\u00e9coratrice d\u2019int\u00e9rieur install\u00e9e \u00e0 Barcelone, consid\u00e8re le retour des vacances comme un nouveau d\u00e9part. \u201cC\u2019est comme une ann\u00e9e qui s\u2019ouvre,\u201d dit-elle. \u201cSeptembre est un mois cr\u00e9atif. C\u2019est un moment o\u00f9 l\u2019on se sent plus ouvert au changement, o\u00f9 l\u2019on peut tirer profit de l\u2019\u00e9nergie retrouv\u00e9e durant les vacances pour faire progresser nos vies.\u201d C\u2019est pourquoi elle commence par proc\u00e9der \u00e0 de petits am\u00e9nagements dans son atelier et sa maison\u00a0: elle bouge les meubles, r\u00e9organise les photos, les livres et les plantes. \u201cComme \u00e7a,\u201d explique-t-elle, \u201cj\u2019entre dans l\u2019automne &#8211; ma saison pr\u00e9f\u00e9r\u00e9e &#8211; avec un nouveau regard sur les choses. \u201d<\/p>\n<p><img class=\"lazyload alignnone wp-image-202884 size-full\" src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome.jpg\" data-orig-src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome.jpg\" width=\"734\" height=\"504\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27734%27%20height%3D%27504%27%20viewBox%3D%270%200%20734%20504%27%3E%3Crect%20width%3D%27734%27%20height%3D%27504%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome-390x268.jpg 390w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome-400x275.jpg 400w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome-546x375.jpg 546w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome-600x412.jpg 600w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/Nikki-MyscandinavianHiome.jpg 734w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/p>\n<p><strong>Niki Brantmark<\/strong>, auteur du blog <a href=\"http:\/\/www.myscandinavianhome.com\/\"><em>My Scandinavian Home<\/em> <\/a>consacr\u00e9 \u00e0 la d\u00e9coration int\u00e9rieure et qu\u2019elle tient depuis sa demeure su\u00e9doise, son pays d\u2019adoption, consid\u00e8re qu\u2019un espace bien organis\u00e9 aide \u00e0 la transition. \u201cLe jour de la reprise, je commence toujours par ranger mon bureau pour disposer d\u2019un espace de travail propre et frais. J\u2019enl\u00e8ve les objets \u00ab\u00a0bruyants\u00bb, inutiles ou qui ne me procurent aucun plaisir et j\u2019ajoute diverses choses pour que l\u2019espace soit en accord avec la saison.\u201d Cela s\u2019accompagne souvent de quelques plantes vertes. \u201cOn sait que les plantes purifient l\u2019air et qu\u2019elles participent de notre bien-\u00eatre \u2013 mais attention, rien qui ne demande trop d\u2019arrosage\u00a0! \u2013 C\u2019est un sentiment agr\u00e9able que de faire table rase et de prendre un nouveau d\u00e9part.\u201d<\/p>\n<p><img class=\"lazyload alignnone wp-image-202878 size-full\" src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles.jpg\" data-orig-src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles.jpg\" width=\"734\" height=\"489\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27734%27%20height%3D%27489%27%20viewBox%3D%270%200%20734%20489%27%3E%3Crect%20width%3D%27734%27%20height%3D%27489%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles-390x260.jpg 390w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles-400x266.jpg 400w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles-563x375.jpg 563w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles-600x400.jpg 600w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/misty-floro-paiedles.jpg 734w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/p>\n<p><strong>Misty Floro et PaiEdles (\u00a0<a href=\"https:\/\/www.instagram.com\/morfosis_ph\/\">@morfosis_ph<\/a>),<\/strong> deux d\u00e9corateurs d\u2019int\u00e9rieur install\u00e9s \u00e0 Quez\u00f3n aux Philippines, ont une arme secr\u00e8te\u00a0: Pizza, leur bulldog anglais d\u2019un an. \u201cApr\u00e8s de bonnes vacances, nous surmontons le blues de la reprise en emmenant Pizza au travail. Il bave beaucoup mais il apporte une bonne dose de gait\u00e9 dans les bureaux. C\u2019est lui qui s\u2019occupe de nos tables de travail et de nos vies\u00a0! \u201d<\/p>\n<p>\u201cComment je fais pour reprendre le train-train quotidien apr\u00e8s m\u2019\u00eatre plong\u00e9e dans de longues siestes, berc\u00e9e par le bruit des vagues sur le rivage et r\u00e9veill\u00e9e par la douce brise d\u2019\u00e9t\u00e9 ? \u201d se demande <strong>Greta Arcila,<\/strong> fondatrice et r\u00e9dactrice en chef de la revue <a href=\"http:\/\/www.glocal.mx\/\"><em>Glocal Design<\/em><\/a>, Mexico DF. \u201cC\u2019est un peu <em>Mission Impossible XXI<\/em>, mais on y arrive\u201d.<\/p>\n<p>Elle consid\u00e8re que, face \u00e0 la r\u00e9alit\u00e9, la meilleure approche consiste \u201c\u00e0 y aller petit \u00e0 petit, pour que la routine ne soit pas trop destructrice\u201d. La musique fait partie int\u00e9grante de cette strat\u00e9gie. L\u2019an dernier, alors qu\u2019elle visitait le Salon Habitat de Valence, en Espagne, elle a d\u00e9couvert la station de radio M80. \u201cJ\u2019en suis tomb\u00e9e amoureuse,\u201d dit-elle, \u201cde plus, le d\u00e9calage horaire entre l\u2019Espagne et le Mexique me permet de vaquer \u00e0 mes occupations quotidiennes tout en \u00e9coutant la musique des ann\u00e9es 80 et 90. J\u2019appartiens \u00e0 la G\u00e9n\u00e9ration X, je n\u2019y peux rien.\u201d<\/p>\n<p><img class=\"lazyload alignnone wp-image-202866\" src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/greta-arcila.jpg\" data-orig-src=\"http:\/\/www.vibia.com\/wp-content\/uploads\/2017\/09\/greta-arcila.jpg\" width=\"360\" height=\"457\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27360%27%20height%3D%27457%27%20viewBox%3D%270%200%20360%20457%27%3E%3Crect%20width%3D%27360%27%20height%3D%27457%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/greta-arcila-295x375.jpg 295w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/greta-arcila-307x390.jpg 307w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/greta-arcila-400x508.jpg 400w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/greta-arcila-600x762.jpg 600w, https:\/\/vibia.dev\/wp-content\/uploads\/2017\/09\/greta-arcila.jpg 734w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/p>\n<p>Quand elle arrive au bureau, elle commence par chercher sur ITunes quelques morceaux classiques pour mieux se concentrer. \u201cEt je prends soudain conscience que j\u2019ai retrouv\u00e9 la routine. Je me sens m\u00eame pr\u00eate \u00e0 retourner au gymnase pour perdre ces kilos que j\u2019ai pris durant les journ\u00e9es pass\u00e9es \u00e0 r\u00eavasser sans me soucier des calories\u201d.<\/p>\n<p><strong>Et vous\u00a0? <\/strong>\u00a0Nous aimerions savoir quelles sont vos astuces et recommandations pour affronter la reprise quand les vacances se terminent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9t\u00e9 est le moment o\u00f9 l\u2019on s\u2019\u00e9vade\u00a0: on fait un break pour \u00e9chapper \u00e0 la routine, on se d\u00e9tend, on se ressource. Mais quand les vacances se terminent, il est parfois difficile de retrouver [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":202959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[866],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/posts\/202559"}],"collection":[{"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/comments?post=202559"}],"version-history":[{"count":5,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/posts\/202559\/revisions"}],"predecessor-version":[{"id":202981,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/posts\/202559\/revisions\/202981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/media\/202959"}],"wp:attachment":[{"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/media?parent=202559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/categories?post=202559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vibia.dev\/fr\/wp-json\/wp\/v2\/tags?post=202559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}